{"id":59426,"date":"2025-08-22T00:13:00","date_gmt":"2025-08-22T03:13:00","guid":{"rendered":"https:\/\/elurbanoweb.com.ar\/diario\/?p=59426"},"modified":"2025-08-22T00:13:00","modified_gmt":"2025-08-22T03:13:00","slug":"personal-del-cic-san-carlos-llevo-adelante-una-jornada-de-vacunacion-en-terreno","status":"publish","type":"post","link":"http:\/\/elurbanoweb.com.ar\/diario\/personal-del-cic-san-carlos-llevo-adelante-una-jornada-de-vacunacion-en-terreno\/","title":{"rendered":"Personal del CIC San Carlos llev\u00f3 adelante una jornada de vacunaci\u00f3n en terreno"},"content":{"rendered":"<p>La Secretar\u00eda de Salud de la Municipalidad de La Banda, a trav\u00e9s del personal del CIC San Carlos, realiz\u00f3 un operativo de vacunaci\u00f3n en el sector. La actividad estuvo destinada a personas con factores de riesgo y con dificultades para movilizarse, garantizando as\u00ed el acceso a la salud a los vecinos que m\u00e1s lo necesitan.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-59427 size-full\" src=\"http:\/\/elurbanoweb.com.ar\/diario\/wp-content\/uploads\/2025\/08\/carlos1.jpg\" alt=\"\" width=\"1010\" height=\"567\" srcset=\"http:\/\/elurbanoweb.com.ar\/diario\/wp-content\/uploads\/2025\/08\/carlos1.jpg 1010w, http:\/\/elurbanoweb.com.ar\/diario\/wp-content\/uploads\/2025\/08\/carlos1-300x168.jpg 300w, http:\/\/elurbanoweb.com.ar\/diario\/wp-content\/uploads\/2025\/08\/carlos1-150x84.jpg 150w\" sizes=\"auto, (max-width: 1010px) 100vw, 1010px\" \/><\/p>\n<p><!--more--><\/p>\n<p>Durante la jornada tambi\u00e9n se efectuaron controles de signos vitales, reforzando el acompa\u00f1amiento sanitario y la prevenci\u00f3n en la comunidad de la ciudad de La Banda.<\/p>\n<p>Al respecto, el secretario de Salud, C\u00e9sar Scabuzzo, destac\u00f3: \u201cEstas acciones reflejan nuestro compromiso con una salud m\u00e1s cercana y accesible, donde cada vecino pueda contar con el acompa\u00f1amiento del sistema municipal, sin importar sus condiciones de movilidad. Seguimos trabajando para que la salud llegue a cada hogar de la ciudad\u201d.<\/p>\n<p>Finalmente, cabe resaltar que estas pol\u00edticas se enmarcan en la gesti\u00f3n del intendente Roger El\u00edas Nediani, que tiene a la salud del vecino como un eje central de gobierno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda de Salud de la Municipalidad de La Banda, a trav\u00e9s del personal del CIC San Carlos, realiz\u00f3 un operativo de vacunaci\u00f3n en el sector. La actividad estuvo destinada&hellip; <\/p>\n","protected":false},"author":1,"featured_media":59427,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-59426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-banda"],"_links":{"self":[{"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/posts\/59426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/comments?post=59426"}],"version-history":[{"count":1,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/posts\/59426\/revisions"}],"predecessor-version":[{"id":59428,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/posts\/59426\/revisions\/59428"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/media\/59427"}],"wp:attachment":[{"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/media?parent=59426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/categories?post=59426"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/tags?post=59426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}