{"id":59449,"date":"2025-08-22T15:11:45","date_gmt":"2025-08-22T18:11:45","guid":{"rendered":"https:\/\/elurbanoweb.com.ar\/diario\/?p=59449"},"modified":"2025-08-22T15:11:45","modified_gmt":"2025-08-22T18:11:45","slug":"anuncian-el-2-encuentro-provincial-de-educacion-para-la-salud-2025","status":"publish","type":"post","link":"http:\/\/elurbanoweb.com.ar\/diario\/anuncian-el-2-encuentro-provincial-de-educacion-para-la-salud-2025\/","title":{"rendered":"Anuncian el 2\u00b0 Encuentro Provincial de Educaci\u00f3n para la Salud 2025"},"content":{"rendered":"<p>Bajo el lema \u201cEducaci\u00f3n para la salud sin fronteras: del territorio al algoritmo\u201d, las autoridades del Ministerio de Salud, de la UNSE y la UCSE anunciaron el 2\u00b0 Encuentro Provincial de Educaci\u00f3n para la Salud 2025, en el marco del D\u00eda de las y los Educadores para la Salud, que se realizar\u00e1 pr\u00f3ximo el lunes 1\u00b0 de septiembre, en el Auditorio \u201cDr. Ram\u00f3n Carrillo\u201d de la cartera sanitaria.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-59450 size-large\" src=\"http:\/\/elurbanoweb.com.ar\/diario\/wp-content\/uploads\/2025\/08\/anuncian-1024x678.jpg\" alt=\"\" width=\"1024\" height=\"678\" srcset=\"http:\/\/elurbanoweb.com.ar\/diario\/wp-content\/uploads\/2025\/08\/anuncian-1024x678.jpg 1024w, http:\/\/elurbanoweb.com.ar\/diario\/wp-content\/uploads\/2025\/08\/anuncian-300x199.jpg 300w, http:\/\/elurbanoweb.com.ar\/diario\/wp-content\/uploads\/2025\/08\/anuncian-150x99.jpg 150w, http:\/\/elurbanoweb.com.ar\/diario\/wp-content\/uploads\/2025\/08\/anuncian-1536x1017.jpg 1536w, http:\/\/elurbanoweb.com.ar\/diario\/wp-content\/uploads\/2025\/08\/anuncian.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><!--more--><\/p>\n<p>El encuentro est\u00e1 destinado a estudiantes, docentes y profesionales de educaci\u00f3n para la salud, comunicaci\u00f3n social y carreras vinculadas al \u00e1rea de la salud, as\u00ed como a equipos del sector p\u00fablico y privado.<\/p>\n<p>El director de Salud Comunitaria, Lic. Gonzalo Ter\u00e1n, explic\u00f3 que \u201cla jornada se desarrollar\u00e1 desde las 8.30 hs. y ser\u00e1 transmitida por Telesalud para los equipos del interior, con la participaci\u00f3n de autoridades provinciales, acad\u00e9micas, equipos interdisciplinarios de salud y comunicadores sociales\u201d. El programa incluye conversatorios sobre salud y redes sociales, promoci\u00f3n en la era digital y \u00e9tica en la comunicaci\u00f3n en salud.<\/p>\n<p>Por su parte, el secretario de Salud, Dr. Gustavo Sabalza, expres\u00f3 que el encuentro fortalece la capacidad pedag\u00f3gica y comunicacional de los educadores para la salud, pilares fundamentales en la promoci\u00f3n de h\u00e1bitos saludables y en el autocuidado de la poblaci\u00f3n\u201d.<\/p>\n<p>La ministra de Salud, Lic. Natividad Nassif, remarc\u00f3 la centralidad de la educaci\u00f3n y la promoci\u00f3n en la salud p\u00fablica: \u201cEducar y promover la salud hoy significa tambi\u00e9n trabajar con redes sociales y procesos comunicacionales. Un sistema p\u00fablico de salud tiene tres objetivos: promover, prevenir y asistir. Los dos primeros est\u00e1n profundamente atravesados por la educaci\u00f3n y la comunicaci\u00f3n es una herramienta poderosa para generar cambios en los estilos de vida y entornos m\u00e1s saludables\u201d.<\/p>\n<p>El rector de la UCSE, Ing. Luis Lucena, destac\u00f3 la articulaci\u00f3n entre el sistema sanitario y el acad\u00e9mico y asegur\u00f3 que la salud tambi\u00e9n se comunica. \u201cLa territorialidad f\u00edsica en salud se complementa con una territorialidad digital, y es all\u00ed donde debemos formar a nuestros estudiantes y ciudadanos\u201d.<\/p>\n<p>Finalmente, la vicerrectora de la UNSE, Lic. Marcela Ju\u00e1rez, subray\u00f3 que la importancia de la tecnolog\u00eda que ampl\u00eda la llegada, complementa y permite un trabajo m\u00e1s equitativo y cercano a la comunidad en territorio\u201d.<\/p>\n<p>La participaci\u00f3n es gratuita, con inscripci\u00f3n previa hasta el 29 de agosto en: https:\/\/forms.gle\/PcGfrZvAFh7NXJ9TA.<\/p>\n<p>Se entregar\u00e1 certificado de asistencia digital a partir de las 72 hs. posteriores al encuentro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bajo el lema \u201cEducaci\u00f3n para la salud sin fronteras: del territorio al algoritmo\u201d, las autoridades del Ministerio de Salud, de la UNSE y la UCSE anunciaron el 2\u00b0 Encuentro Provincial&hellip; <\/p>\n","protected":false},"author":1,"featured_media":59450,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-59449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"_links":{"self":[{"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/posts\/59449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/comments?post=59449"}],"version-history":[{"count":1,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/posts\/59449\/revisions"}],"predecessor-version":[{"id":59451,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/posts\/59449\/revisions\/59451"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/media\/59450"}],"wp:attachment":[{"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/media?parent=59449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/categories?post=59449"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/tags?post=59449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}