{"id":70149,"date":"2026-05-13T10:16:31","date_gmt":"2026-05-13T13:16:31","guid":{"rendered":"https:\/\/elurbanoweb.com.ar\/diario\/?p=70149"},"modified":"2026-05-13T10:16:31","modified_gmt":"2026-05-13T13:16:31","slug":"se-viene-el-10-aniversario-del-rxp-en-las-termas","status":"publish","type":"post","link":"http:\/\/elurbanoweb.com.ar\/diario\/se-viene-el-10-aniversario-del-rxp-en-las-termas\/","title":{"rendered":"Se viene el 10\u00b0 aniversario del RXP en Las Termas"},"content":{"rendered":"<p>El motociclismo nacional vuelve a tener su epicentro en Termas de R\u00edo Hondo. Desde este jueves 14 y hasta el domingo 17 de mayo, se llevar\u00e1 a cabo la d\u00e9cima edici\u00f3n del RXP, un evento que se ha consolidado como una referencia para los amantes de las dos ruedas en la regi\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-70150 size-large\" src=\"http:\/\/elurbanoweb.com.ar\/diario\/wp-content\/uploads\/2026\/05\/rx-1024x726.png\" alt=\"\" width=\"1024\" height=\"726\" srcset=\"http:\/\/elurbanoweb.com.ar\/diario\/wp-content\/uploads\/2026\/05\/rx-1024x726.png 1024w, http:\/\/elurbanoweb.com.ar\/diario\/wp-content\/uploads\/2026\/05\/rx-300x213.png 300w, http:\/\/elurbanoweb.com.ar\/diario\/wp-content\/uploads\/2026\/05\/rx-150x106.png 150w, http:\/\/elurbanoweb.com.ar\/diario\/wp-content\/uploads\/2026\/05\/rx-1536x1090.png 1536w, http:\/\/elurbanoweb.com.ar\/diario\/wp-content\/uploads\/2026\/05\/rx.png 1748w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><!--more--><\/p>\n<p>La organizaci\u00f3n ha confirmado que esta fecha aniversario contar\u00e1 con un nivel de exigencia t\u00e9cnica superior, dise\u00f1ada tanto para pilotos experimentados que buscan bajar sus tiempos, como para aquellos que est\u00e1n dando sus \u201cprimeras armas\u201d en el motociclismo de velocidad.<\/p>\n<p>Cronograma: cuatro d\u00edas de pura actividad<br \/>\nPara esta edici\u00f3n especial, se ha dispuesto una agenda completa que permitir\u00e1 a los protagonistas aprovechar al m\u00e1ximo las bondades del circuito santiague\u00f1o:<\/p>\n<p>Jueves 14: Jornada administrativa. Se realizar\u00e1n las acreditaciones y la asignaci\u00f3n de boxes. Adem\u00e1s, los pilotos tendr\u00e1n la oportunidad de realizar el reconocimiento de pista a pie, un ritual clave para estudiar los radios de giro y el estado del asfalto.<\/p>\n<p>Viernes 15 al Domingo 17: Tres d\u00edas de pista habilitada de 9:00 a 18:30 horas.<\/p>\n<p>Durante el fin de semana se desarrollar\u00e1n un total de quince tandas, que incluyen:<\/p>\n<p>Giros libres para puesta a punto.<\/p>\n<p>Tandas cronometradas para medir el rendimiento.<\/p>\n<p>Sesiones de \u201cdemo\u201d para el p\u00fablico y participantes.<\/p>\n<p>Im\u00e1n para el turismo deportivo<br \/>\nCon un \u201cn\u00famero importante de inscriptos\u201d provenientes de distintos puntos del pa\u00eds, el evento promete no solo un espect\u00e1culo deportivo de alto nivel, sino tambi\u00e9n un impacto positivo en la hoteler\u00eda y gastronom\u00eda de la ciudad termal. La entrada de los equipos y la vibraci\u00f3n de los motores en boxes marcar\u00e1n el pulso de un fin de semana que celebra diez a\u00f1os de pasi\u00f3n por la velocidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El motociclismo nacional vuelve a tener su epicentro en Termas de R\u00edo Hondo. Desde este jueves 14 y hasta el domingo 17 de mayo, se llevar\u00e1 a cabo la d\u00e9cima&hellip; <\/p>\n","protected":false},"author":1,"featured_media":70150,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-70149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/posts\/70149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/comments?post=70149"}],"version-history":[{"count":1,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/posts\/70149\/revisions"}],"predecessor-version":[{"id":70151,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/posts\/70149\/revisions\/70151"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/media\/70150"}],"wp:attachment":[{"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/media?parent=70149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/categories?post=70149"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elurbanoweb.com.ar\/diario\/wp-json\/wp\/v2\/tags?post=70149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}